{"id":149962,"date":"2021-09-30T01:45:00","date_gmt":"2021-09-29T23:45:00","guid":{"rendered":"https:\/\/www.region-schwabach.de\/wordpress\/?p=149962"},"modified":"2021-09-29T22:32:36","modified_gmt":"2021-09-29T20:32:36","slug":"weiterer-impfen-to-go-termin-in-schwabach-am-donnerstag-den-30-september-2021","status":"publish","type":"post","link":"https:\/\/www.region-schwabach.de\/wordpress\/weiterer-impfen-to-go-termin-in-schwabach-am-donnerstag-den-30-september-2021\/","title":{"rendered":"Weiterer &#8222;Impfen to go&#8220;-Termin in Schwabach am Donnerstag, den 30. September 2021"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"149962\" class=\"elementor elementor-149962\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-678181b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"678181b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6b34026\" data-id=\"6b34026\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fea1cd elementor-widget elementor-widget-wp-widget-advads_ad_widget\" data-id=\"5fea1cd\" data-element_type=\"widget\" data-widget_type=\"wp-widget-advads_ad_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"regio-3877532700\"><div class=\"regio-adlabel\">Werbung<\/div><center><a href=\"https:\/\/a.partner-versicherung.de\/click.php?partner_id=19992&ad_id=1578&deep=kreditkarten\"  target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/a.partner-versicherung.de\/view.php?partner_id=19992&ad_id=1578\" ><\/a><\/center><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-443ab98 elementor-widget elementor-widget-text-editor\" data-id=\"443ab98\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3>Weiterer &#8222;Impfen to go&#8220;-Termin in Schwabach am Donnerstag, den 30. September 2021<\/h3><p><span style=\"font-size: 12pt;\">Schwabach &#8211; Am Donnerstag, den 30. September 2021, findet in Schwabach ein weiterer &#8222;Impfen to go&#8220; &#8211; Termin in Schwabach statt. <\/span><\/p><h3>Der Sondertermin:<\/h3><ul style=\"list-style-type: disc;\"><li><span style=\"font-size: 12pt;\">ORO-Einkaufszentrum, Am Falbenholzweg 15, am Donnerstag, den 30. September 2021, von 14.00 bis 19.00 Uhr\u00a0<\/span><\/li><\/ul><p><strong><span style=\"font-size: 12pt;\">Geimpft wird nur mit BionTec. Der Zweitimpftermin findet sechs Wochen sp\u00e4ter am 23. Oktober im Impfzentrum statt<\/span><\/strong><\/p><h3>Schwabacher Impfzentrum<\/h3><p><span style=\"font-size: 12pt;\">Ohne Anmeldung und Termin k\u00f6nnen sich Impfwillige auch im Schwabacher Impfzentrum weiterhin impfen lassen. Im September 2021 stehen in folgenden Zeitr\u00e4umen die T\u00fcren f\u00fcr jede und jeden offen: <\/span><\/p><ul style=\"list-style-type: disc;\"><li><span style=\"font-size: 12pt;\">samstags von 09.00 Uhr bis 13.00 Uhr\u00a0<\/span><\/li><\/ul><p><span style=\"font-size: 12pt;\">Auch Nicht-Schwabacher und B\u00fcrgerinnen und B\u00fcrger, die ihre 1. Impfung bei einem Arzt erhalten haben, k\u00f6nnen sich hier impfen lassen. W\u00e4hrend dieser \u00d6ffnungszeiten wird nur mit dem Impfstoff von BionTech geimpft. <br \/><\/span><\/p><p><span style=\"font-size: 12pt;\">Von den oben genannten Zeiten bleiben die Termine f\u00fcr eine bereits vereinbarte Zweitimpfung unber\u00fchrt. Termine f\u00fcr eine Dritt-Impfung werden im Impfzentrum nicht vergeben.\u00a0<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cc9469 elementor-widget elementor-widget-shortcode\" data-id=\"7cc9469\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><center><a href=\"https:\/\/a.partner-versicherung.de\/click.php?partner_id=19992&ad_id=441&deep=kfz-versicherung\"  target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/a.partner-versicherung.de\/view.php?partner_id=19992&ad_id=441\" ><\/a><\/center><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c834d7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0c834d7\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-325f51f elementor-widget elementor-widget-google_maps\" data-id=\"325f51f\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=H%C3%BCttersb%C3%BChlstra%C3%9Fe%2023%2C%20Schwabach%2C%20Deutschland&#038;t=m&#038;z=17&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"H\u00fcttersb\u00fchlstra\u00dfe 23, Schwabach, Deutschland\"\n\t\t\t\t\taria-label=\"H\u00fcttersb\u00fchlstra\u00dfe 23, Schwabach, Deutschland\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f141625\" data-id=\"f141625\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa635e8 elementor-widget elementor-widget-heading\" data-id=\"aa635e8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Schnell vergleichen und sparen!<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-380778c elementor-widget elementor-widget-wp-widget-advads_ad_widget\" data-id=\"380778c\" data-element_type=\"widget\" data-widget_type=\"wp-widget-advads_ad_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"regio-3394314506\"><div class=\"regio-adlabel\">Werbung<\/div><!-- Beginn https:\/\/www.financeads.net\/-Code --><a href=\"https:\/\/www.financeads.net\/tc.php?t=36648C236142529B\" target=\"_blank\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.financeads.net\/tb.php?t=36648V236142529B&https=1\" alt=\"\" border=\"0\" width=\"300\" height=\"250\"><\/a><!-- Ende https:\/\/www.financeads.net\/-Code --><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd26aa5 elementor-widget elementor-widget-wp-widget-advads_ad_widget\" data-id=\"bd26aa5\" data-element_type=\"widget\" data-widget_type=\"wp-widget-advads_ad_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"regio-3893611590\"><div class=\"regio-adlabel\">Werbung<\/div><!-- Beginn https:\/\/www.financeads.net\/-Code --><a href=\"https:\/\/www.financeads.net\/tc.php?t=36648C42614510B\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.financeads.net\/tb.php?t=36648V42614510B&https=1\" alt=\"\" border=\"0\" width=\"200\" height=\"300\"><\/a><!-- Ende https:\/\/www.financeads.net\/-Code --><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abfc6b5 elementor-widget elementor-widget-wp-widget-advads_ad_widget\" data-id=\"abfc6b5\" data-element_type=\"widget\" data-widget_type=\"wp-widget-advads_ad_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"regio-2667844414\"><div class=\"regio-adlabel\">Werbung<\/div><!-- Beginn https:\/\/www.financeads.net\/-Code --><a href=\"https:\/\/www.financeads.net\/tc.php?t=36648C205040072B\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.financeads.net\/tb.php?t=36648V205040072B&https=1\" alt=\"\" border=\"0\" width=\"300\" height=\"250\"><\/a><!-- Ende https:\/\/www.financeads.net\/-Code --><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b68655 elementor-widget elementor-widget-wp-widget-advads_ad_widget\" data-id=\"9b68655\" data-element_type=\"widget\" data-widget_type=\"wp-widget-advads_ad_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"regio-2281777946\"><div class=\"regio-adlabel\">Werbung<\/div><!-- Beginn https:\/\/www.financeads.net\/-Code --><a href=\"https:\/\/www.financeads.net\/tc.php?t=36648C271460142B\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.financeads.net\/tb.php?t=36648V271460142B&https=1\" alt=\"PETPROTECT_Hund&Katze_Banner\" border=\"0\" width=\"250\" height=\"250\"><\/a><!-- Ende https:\/\/www.financeads.net\/-Code --><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Weiterer &#8222;Impfen to go&#8220;-Termin in Schwabach am Donnerstag, den 30. September 2021 Schwabach &#8211; Am Donnerstag, den 30. September 2021, findet in Schwabach ein weiterer &#8222;Impfen to go&#8220; &#8211; Termin in Schwabach statt. Der Sondertermin: <a class=\"mh-excerpt-more\" href=\"https:\/\/www.region-schwabach.de\/wordpress\/weiterer-impfen-to-go-termin-in-schwabach-am-donnerstag-den-30-september-2021\/\" title=\"Weiterer &#8222;Impfen to go&#8220;-Termin in Schwabach am Donnerstag, den 30. September 2021\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":149963,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_cbd_carousel_blocks":"[]","footnotes":""},"categories":[16,287,61],"tags":[16994,16993,60,13293,4422,16726,14468,14472,475,10334,19,3012,3151],"class_list":{"0":"post-149962","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-aktuell","8":"category-jugend-und-familie","9":"category-rathaus","10":"tag-30-september-2021","11":"tag-30-09-2021","12":"tag-am-falbenholzweg","13":"tag-corona-faelle","14":"tag-huttersbuehlstrasse","15":"tag-impfen-to-go","16":"tag-impfung","17":"tag-impfzentrum","18":"tag-oro","19":"tag-oro-einkaufszentrum","20":"tag-schwabach","21":"tag-stadt","22":"tag-stadt-schwabach"},"_links":{"self":[{"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/posts\/149962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/comments?post=149962"}],"version-history":[{"count":0,"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/posts\/149962\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/media\/149963"}],"wp:attachment":[{"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/media?parent=149962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/categories?post=149962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/tags?post=149962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}