{"id":236639,"date":"2024-07-03T00:07:00","date_gmt":"2024-07-02T22:07:00","guid":{"rendered":"https:\/\/www.region-schwabach.de\/wordpress\/?p=236639"},"modified":"2024-07-03T01:05:15","modified_gmt":"2024-07-02T23:05:15","slug":"illegales-strassenrennen-auf-bundesstrasse-bei-weissenburg","status":"publish","type":"post","link":"https:\/\/www.region-schwabach.de\/wordpress\/illegales-strassenrennen-auf-bundesstrasse-bei-weissenburg\/","title":{"rendered":"Illegales Stra\u00dfenrennen auf Bundesstra\u00dfe bei Wei\u00dfenburg"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"236639\" class=\"elementor elementor-236639\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1cuv9jr elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1cuv9jr\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-q5zak7b\" data-id=\"q5zak7b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dcef279 elementor-widget elementor-widget-wp-widget-advads_ad_widget\" data-id=\"dcef279\" data-element_type=\"widget\" data-widget_type=\"wp-widget-advads_ad_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"regio-726386823\"><div class=\"regio-adlabel\">Werbung<\/div><center><a href=\"https:\/\/a.partner-versicherung.de\/click.php?partner_id=19992&ad_id=1578&deep=kreditkarten\"  target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/a.partner-versicherung.de\/view.php?partner_id=19992&ad_id=1578\" ><\/a><\/center><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4daeae elementor-widget elementor-widget-text-editor\" data-id=\"a4daeae\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3>Illegales Stra\u00dfenrennen\u00a0<\/h3><p><span style=\"font-size: 12pt;\">Wei\u00dfenburg &#8211; Am Montagabend, den 01.07.2024, lieferten sich zwei PKW-Fahrer auf der Bundesstra\u00dfe 2 gegen 18.40 Uhr ein illegales Stra\u00dfenrennen. Ein wei\u00dfer und ein gr\u00fcner Audi fuhren, auf H\u00f6he Wei\u00dfenburg beginnend in Richtung N\u00fcrnberg, mit stark \u00fcberh\u00f6hter Geschwindigkeit, \u00fcberholten dabei mehrere Male &#8211; trotz Gegenverkehr im einspurigen Bereich.\u00a0<\/span><\/p><p><span style=\"font-size: 12pt;\">Durch ihre \u00e4u\u00dferst riskante Fahrweise zwangen sie andere Verkehrsteilnehmer zu Bremsman\u00f6vern, um eine Kollision mit den entgegenkommenden Fahrzeugen zu verhindern. Der Polizei gelang es schlie\u00dflich auf H\u00f6he von Rednitzhembach den Fahrer des wei\u00dfen Audi anzuhalten, der Fahrer des gr\u00fcnen Audi ist bis jetzt unbekannt.\u00a0<\/span><\/p><h3>Polizei bittet um Mithilfe\u00a0<\/h3><p><span style=\"font-size: 12pt;\">Die Polizei bittet Zeugen die Angaben zu diesem Vorfall machen k\u00f6nnen, insbesondere wird ein stark gef\u00e4hrdeter PKW-Fahrer, der Richtung Wei\u00dfenburg fuhr gesucht, sich mit der Polizei in Wei\u00dfenburg unter der Telefonnummer 09141-86 87-0 in Verbindung zu setzen.\u00a0<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c3f9de elementor-widget elementor-widget-shortcode\" data-id=\"6c3f9de\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><center><a href=\"https:\/\/a.partner-versicherung.de\/click.php?partner_id=19992&ad_id=441&deep=kfz-versicherung\"  target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/a.partner-versicherung.de\/view.php?partner_id=19992&ad_id=441\" ><\/a><\/center><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ace1283 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ace1283\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06e666a elementor-widget elementor-widget-google_maps\" data-id=\"06e666a\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Wei%C3%9Fenburg%2C%20Deutschland&#038;t=m&#038;z=13&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Wei\u00dfenburg, Deutschland\"\n\t\t\t\t\taria-label=\"Wei\u00dfenburg, Deutschland\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4ce46fb\" data-id=\"4ce46fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38f4e35 elementor-widget elementor-widget-heading\" data-id=\"38f4e35\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Schnell vergleichen und sparen!<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92c49bc elementor-widget elementor-widget-wp-widget-advads_ad_widget\" data-id=\"92c49bc\" data-element_type=\"widget\" data-widget_type=\"wp-widget-advads_ad_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"regio-1538721165\"><div class=\"regio-adlabel\">Werbung<\/div><!-- Beginn https:\/\/www.financeads.net\/-Code --><a href=\"https:\/\/www.financeads.net\/tc.php?t=36648C236142529B\" target=\"_blank\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.financeads.net\/tb.php?t=36648V236142529B&https=1\" alt=\"\" border=\"0\" width=\"300\" height=\"250\"><\/a><!-- Ende https:\/\/www.financeads.net\/-Code --><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb0c78c elementor-widget elementor-widget-wp-widget-advads_ad_widget\" data-id=\"cb0c78c\" data-element_type=\"widget\" data-widget_type=\"wp-widget-advads_ad_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"regio-2446247619\"><div class=\"regio-adlabel\">Werbung<\/div><!-- Beginn https:\/\/www.financeads.net\/-Code --><a href=\"https:\/\/www.financeads.net\/tc.php?t=36648C42614510B\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.financeads.net\/tb.php?t=36648V42614510B&https=1\" alt=\"\" border=\"0\" width=\"200\" height=\"300\"><\/a><!-- Ende https:\/\/www.financeads.net\/-Code --><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31c9ced elementor-widget elementor-widget-wp-widget-advads_ad_widget\" data-id=\"31c9ced\" data-element_type=\"widget\" data-widget_type=\"wp-widget-advads_ad_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"regio-3110101469\"><div class=\"regio-adlabel\">Werbung<\/div><!-- Beginn https:\/\/www.financeads.net\/-Code --><a href=\"https:\/\/www.financeads.net\/tc.php?t=36648C205040072B\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.financeads.net\/tb.php?t=36648V205040072B&https=1\" alt=\"\" border=\"0\" width=\"300\" height=\"250\"><\/a><!-- Ende https:\/\/www.financeads.net\/-Code --><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0344b9f elementor-widget elementor-widget-wp-widget-advads_ad_widget\" data-id=\"0344b9f\" data-element_type=\"widget\" data-widget_type=\"wp-widget-advads_ad_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"regio-1556665674\"><div class=\"regio-adlabel\">Werbung<\/div><!-- Beginn https:\/\/www.financeads.net\/-Code --><a href=\"https:\/\/www.financeads.net\/tc.php?t=36648C271460142B\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.financeads.net\/tb.php?t=36648V271460142B&https=1\" alt=\"PETPROTECT_Hund&Katze_Banner\" border=\"0\" width=\"250\" height=\"250\"><\/a><!-- Ende https:\/\/www.financeads.net\/-Code --><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Illegales Stra\u00dfenrennen\u00a0 Wei\u00dfenburg &#8211; Am Montagabend, den 01.07.2024, lieferten sich zwei PKW-Fahrer auf der Bundesstra\u00dfe 2 gegen 18.40 Uhr ein illegales Stra\u00dfenrennen. Ein wei\u00dfer und ein gr\u00fcner Audi fuhren, auf H\u00f6he Wei\u00dfenburg beginnend in Richtung <a class=\"mh-excerpt-more\" href=\"https:\/\/www.region-schwabach.de\/wordpress\/illegales-strassenrennen-auf-bundesstrasse-bei-weissenburg\/\" title=\"Illegales Stra\u00dfenrennen auf Bundesstra\u00dfe bei Wei\u00dfenburg\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":236640,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_cbd_carousel_blocks":"[]","footnotes":""},"categories":[22135,21581,21316,22879,22614,22354,21838,15],"tags":[25737,961,429,1464,541,555,25769,35,463,981,493,25770,8507,585,249],"class_list":{"0":"post-236639","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-polizei-april-2023","8":"category-polizei-februar-2023","9":"category-polizei-januar-2023","10":"category-polizei-juli-2023","11":"category-polizei-juni-2023","12":"category-polizei-mai-2023","13":"category-polizei-maerz-2023","14":"category-polizeimeldungen","15":"tag-01-07-2024","16":"tag-audi","17":"tag-b2","18":"tag-bremsmanoever","19":"tag-bundesstrasse-2","20":"tag-gegenverkehr","21":"tag-illegales-strassenrennen","22":"tag-nuernberg","23":"tag-pkw","24":"tag-polizei","25":"tag-rednitzhembach","26":"tag-riskante-fahrweise","27":"tag-ueberhoehte-geschwindigkeit-2","28":"tag-ueberholmanoever","29":"tag-weissenburg"},"_links":{"self":[{"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/posts\/236639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/comments?post=236639"}],"version-history":[{"count":4,"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/posts\/236639\/revisions"}],"predecessor-version":[{"id":236644,"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/posts\/236639\/revisions\/236644"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/media\/236640"}],"wp:attachment":[{"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/media?parent=236639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/categories?post=236639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.region-schwabach.de\/wordpress\/wp-json\/wp\/v2\/tags?post=236639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}